{"id":198466,"date":"2023-10-18T14:51:34","date_gmt":"2023-10-18T11:51:34","guid":{"rendered":"https:\/\/ronahi.tv\/ar\/?p=198466"},"modified":"2023-10-18T14:51:34","modified_gmt":"2023-10-18T11:51:34","slug":"%d8%ad%d8%b1%d9%83%d8%a9-%d8%a7%d9%84%d9%85%d8%b1%d8%a3%d8%a9-%d8%a7%d9%84%d9%83%d8%b1%d8%af%d9%8a%d8%a9-%d9%81%d9%8a-%d8%a3%d9%88%d8%b1%d9%88%d8%a8%d8%a7-%d9%84%d9%86%d8%aa%d8%a8%d9%86%d9%89-%d8%a7","status":"publish","type":"post","link":"https:\/\/ronahi.tv\/ar\/archives\/198466","title":{"rendered":"\u062d\u0631\u0643\u0629 \u0627\u0644\u0645\u0631\u0623\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629 \u0641\u064a \u0623\u0648\u0631\u0648\u0628\u0627: \u0644\u0646\u062a\u0628\u0646\u0649 \u0627\u0644\u062d\u0645\u0644\u0629 \u0627\u0644\u0639\u0627\u0644\u0645\u064a\u0629 \u0644\u062d\u0631\u064a\u0629 \u0627\u0644\u0642\u0627\u0626\u062f \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0623\u0648\u062c\u0644\u0627\u0646"},"content":{"rendered":"<p style=\"direction: rtl;\"><strong>\u0623\u0639\u0644\u0646\u062a \u062d\u0631\u0643\u0629 \u0627\u0644\u0645\u0631\u0623\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629 \u0641\u064a \u0623\u0648\u0631\u0648\u0628\u0627 \u0639\u0646 \u062a\u0628\u0646\u064a\u0647\u0627 \u0644\u062d\u0645\u0644\u0629 &#8220;<a href=\"https:\/\/ronahi.tv\/ar\/%d9%85%d8%a4%d8%aa%d9%85%d8%b1-%d8%a7%d9%84%d9%85%d8%ac%d8%aa%d9%85%d8%b9-%d8%a7%d9%84%d9%83%d8%b1%d8%af%d9%8a-%d8%a7%d9%84%d8%af%d9%8a%d9%85%d9%82%d8%b1%d8%a7%d8%b7%d9%8a-%d9%81%d9%8a-%d8%a3%d9%88-2\/\">\u0627\u0644\u062d\u0631\u064a\u0629 \u0644\u0644\u0642\u0627\u0626\u062f \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0623\u0648\u062c\u0644\u0627\u0646<\/a>\u060c \u0627\u0644\u062d\u0644 \u0627\u0644\u0633\u064a\u0627\u0633\u064a \u0644\u0644\u0642\u0636\u064a\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629&#8221;\u060c \u0648\u0639\u0628\u0631\u062a \u0639\u0646 \u0625\u064a\u0645\u0627\u0646\u0647\u0627 \u0628\u0623\u0646 \u0627\u0644\u0634\u0639\u0628 \u0633\u064a\u062a\u0648\u062c \u0646\u0636\u0627\u0644\u0647 \u0628\u062a\u062d\u0642\u064a\u0642 \u0627\u0644\u062d\u0631\u064a\u0629 \u0627\u0644\u062c\u0633\u062f\u064a\u0629 \u0644\u0644\u0642\u0627\u0626\u062f.<\/strong><\/p>\n<p style=\"direction: rtl;\">\u0623\u0637\u0644\u0642\u062a \u0627\u0644\u0646\u0642\u0627\u0628\u0627\u062a \u0627\u0644\u0639\u0627\u0644\u0645\u064a\u0629 \u0648\u0627\u0644\u0623\u062d\u0632\u0627\u0628 \u0627\u0644\u0633\u064a\u0627\u0633\u064a\u0629 \u0641\u064a \u0623\u0631\u0628\u0639\u0629\u064d \u0648\u0633\u0628\u0639\u064a\u0646 \u0645\u062f\u064a\u0646\u0629 \u062d\u0648\u0644 \u0627\u0644\u0639\u0627\u0644\u0645 \u0641\u064a \u0627\u0644\u0639\u0627\u0634\u0631\u0650 \u0645\u0646 \u062a\u0634\u0631\u064a\u0646 \u0627\u0644\u0623\u0648\u0644 \u0627\u0644\u062c\u0627\u0631\u064a \u062d\u0645\u0644\u0629 &#8220;\u0627\u0644\u062d\u0631\u064a\u0629 \u0644\u0644\u0642\u0627\u0626\u062f \u0623\u0648\u062c\u0644\u0627\u0646\u060c\u0627\u0644\u062d\u0644 \u0627\u0644\u0633\u064a\u0627\u0633\u064a \u0644\u0644\u0642\u0636\u064a\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629&#8221;.<\/p>\n<p style=\"direction: rtl;\">\u0648\u0641\u064a \u0627\u0644\u0633\u064a\u0627\u0642 \u0623\u0639\u0644\u0646\u062a \u062d\u0631\u0643\u0629 \u0627\u0644\u0645\u0631\u0623\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629 \u0641\u064a \u0623\u0648\u0631\u0648\u0628\u0627 \u0639\u0628\u0631 \u0628\u064a\u0627\u0646\u060c \u062a\u0628\u0646\u064a\u0647\u0627 \u0644\u062d\u0645\u0644\u0629 \u0627\u0644\u062d\u0631\u064a\u0629 \u0625\u0630 \u0623\u0648\u0636\u062d \u0627\u0644\u0628\u064a\u0627\u0646 \u0625\u0646 \u0627\u0646\u0637\u0644\u0627\u0642 \u0627\u0644\u062d\u0645\u0644\u0629 \u0627\u0644\u0639\u0627\u0644\u0645\u064a\u0629 \u0635\u0627\u062f\u0641 \u0627\u0644\u0633\u0646\u0648\u064a\u0629 \u0627\u0644\u062e\u0627\u0645\u0633\u0629 \u0648\u0627\u0644\u0639\u0634\u0631\u064a\u0646 \u0644\u0644\u0645\u0624\u0627\u0645\u0631\u0629 \u0627\u0644\u062f\u0648\u0644\u064a\u0629 \u0636\u062f \u0627\u0644\u0642\u0627\u0626\u062f \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0623\u0648\u062c\u0644\u0627\u0646 \u0639\u0627\u0645 \u0623\u0644\u0641 \u0648\u062a\u0633\u0639\u0645\u0627\u0626\u0629 \u0648\u062b\u0645\u0627\u0646\u064a\u0629 \u0648\u062a\u0633\u0639\u064a\u0646\u060c \u0648\u0627\u0644\u062a\u064a \u0646\u0641\u0630\u0647\u0627 \u0646\u0638\u0627\u0645 \u0627\u0644\u062d\u062f\u0627\u062b\u0629 \u0627\u0644\u0631\u0623\u0633\u0645\u0627\u0644\u064a\u0629 \u0627\u0644\u0639\u0627\u0644\u0645\u064a\u060c \u0645\u0634\u064a\u0631\u0627\u064b \u0623\u0646 \u0627\u0644\u0631\u062f \u0627\u0644\u0623\u0643\u0628\u0631 \u0648\u0627\u0644\u0623\u0643\u062b\u0631 \u0623\u0647\u0645\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0645\u0624\u0627\u0645\u0631\u0629 \u0627\u0644\u062f\u0648\u0644\u064a\u0629 \u0647\u0648 \u0628\u062f\u0627\u064a\u0629 \u0647\u0630\u0647 \u0627\u0644\u062d\u0645\u0644\u0629.<\/p>\n<p style=\"direction: rtl;\">\u0648\u0623\u0648\u0636\u062d \u0627\u0644\u0628\u064a\u0627\u0646 \u0623\u0646 \u0627\u0644\u062a\u0639\u0630\u064a\u0628 \u0648\u0633\u064a\u0627\u0633\u0627\u062a \u0627\u0644\u0639\u0632\u0644\u0629 \u0627\u0644\u062a\u064a \u062a\u0645\u0627\u0631\u0633\u0647\u0627 \u0627\u0644\u0641\u0627\u0634\u064a\u0629 \u0627\u0644\u062a\u0631\u0643\u064a\u0629 \u0639\u0644\u0649 \u0627\u0644\u0642\u0627\u0626\u062f \u0639\u0628\u062f\u0627\u0644\u0644\u0647 \u0623\u0648\u062c\u0644\u0627\u0646 \u0641\u064a \u0625\u0645\u0631\u0627\u0644\u064a\u060c \u062a\u062d\u0648\u0644 \u0625\u0644\u0649 \u0641\u0636\u064a\u062d\u0629 \u0642\u0627\u0646\u0648\u0646\u064a\u0629 \u0644\u064a\u0633 \u0641\u064a \u062f\u0648\u0644\u0629 \u0627\u0644\u0627\u062d\u062a\u0644\u0627\u0644 \u0641\u062d\u0633\u0628\u060c \u0628\u0644 \u0641\u064a \u0627\u0644\u0639\u0627\u0644\u0645 \u0623\u062c\u0645\u0639 \u0623\u064a\u0636\u0627\u064b.<\/p>\n<p style=\"direction: rtl;\">\u062d\u0631\u0643\u0629 \u0627\u0644\u0645\u0631\u0623\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629: \u0643\u0644 \u0645\u062d\u0627\u0648\u0644\u0629 \u0644\u062a\u062f\u0645\u064a\u0631 \u0646\u0638\u0627\u0645 \u0627\u0644\u0639\u0632\u0644\u0629 \u062a\u0644\u0639\u0628 \u062f\u0648\u0631\u0627\u064b \u0641\u064a \u0625\u0631\u0633\u0627\u0621 \u0627\u0644\u062f\u064a\u0645\u0642\u0631\u0627\u0637\u064a\u0629 \u0628\u0627\u0644\u0634\u0631\u0642 \u0627\u0644\u0623\u0648\u0633\u0637<\/p>\n<p style=\"direction: rtl;\">\u0648\u0623\u0643\u062f \u0627\u0644\u0628\u064a\u0627\u0646 \u0623\u0646 \u0647\u0630\u0647 \u062e\u0637\u0648\u0629 \u062a\u0643\u0634\u0641 \u0627\u0644\u0645\u0648\u0627\u0642\u0641 \u0627\u0644\u0645\u0632\u064a\u0641\u0629 \u0648\u063a\u064a\u0631 \u0627\u0644\u0623\u062e\u0644\u0627\u0642\u064a\u0629 \u0648\u0627\u0644\u0645\u0646\u0627\u0641\u0642\u0629 \u0644\u0644\u0645\u0624\u0633\u0633\u0627\u062a \u0648\u0627\u0644\u0645\u0646\u0638\u0645\u0627\u062a \u0627\u0644\u062f\u0648\u0644\u064a\u0629 \u0627\u0644\u062a\u064a \u064a\u0641\u062a\u0631\u0636 \u0623\u0646\u0647\u0627 \u0645\u0633\u0624\u0648\u0644\u0629 \u0639\u0646 &#8220;\u062d\u0645\u0627\u064a\u0629 \u062d\u0642\u0648\u0642 \u0627\u0644\u0625\u0646\u0633\u0627\u0646 \u0648\u0627\u0644\u062f\u064a\u0645\u0642\u0631\u0627\u0637\u064a\u0629&#8221;\u060c \u0648\u0647\u0630\u0647 \u0627\u0644\u062d\u0645\u0644\u0629 \u062a\u0638\u0647\u0631 \u0623\u0646\u0647 \u0631\u063a\u0645 \u0625\u0644\u062a\u0632\u0627\u0645\u0647\u0645 \u0627\u0644\u0635\u0645\u062a\u060c \u0641\u0644\u0646 \u064a\u0644\u062a\u0632\u0645 \u0627\u0644\u0639\u0642\u0644 \u0648\u0627\u0644\u0636\u0645\u064a\u0631 \u0648\u0627\u0644\u0623\u062e\u0644\u0627\u0642 \u0627\u0644\u0625\u0646\u0633\u0627\u0646\u064a\u0629 \u0627\u0644\u0635\u0645\u062a.<\/p>\n<p style=\"direction: rtl;\">\u0645\u0634\u064a\u0631\u0627\u064b \u0623\u0646 \u0643\u0644 \u0645\u062d\u0627\u0648\u0644\u0629 \u0644\u062a\u062f\u0645\u064a\u0631 \u0646\u0638\u0627\u0645 \u0627\u0644\u062a\u0639\u0630\u064a\u0628 \u0648\u0627\u0644\u0639\u0632\u0644\u0629 \u0648\u0627\u0644\u0625\u0628\u0627\u062f\u0629 \u0645\u0646 \u0623\u062c\u0644 \u0636\u0645\u0627\u0646 \u0627\u0644\u062d\u0631\u064a\u0629 \u0627\u0644\u062c\u0633\u062f\u064a\u0629 \u0644\u0644\u0642\u0627\u0626\u062f \u0648\u062a\u062d\u0642\u064a\u0642 \u062d\u0644 \u062f\u064a\u0645\u0642\u0631\u0627\u0637\u064a \u0644\u0644\u0642\u0636\u064a\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629\u060c \u0633\u0648\u0641 \u062a\u0644\u0639\u0628 \u062f\u0648\u0631\u0627\u064b \u0643\u0628\u064a\u0631\u0627\u064b \u0641\u064a \u0625\u0631\u0633\u0627\u0621 \u0627\u0644\u062f\u064a\u0645\u0642\u0631\u0627\u0637\u064a\u0629 \u0641\u064a \u0627\u0644\u0634\u0631\u0642 \u0627\u0644\u0623\u0648\u0633\u0637 \u0648\u062d\u062a\u0649 \u0627\u0644\u062f\u064a\u0645\u0642\u0631\u0627\u0637\u064a\u0629 \u0627\u0644\u0639\u0627\u0644\u0645\u064a\u0629.<\/p>\n<p style=\"direction: rtl;\">\u0627\u0644\u0628\u064a\u0627\u0646 \u0646\u0648\u0647 \u0623\u0646 \u0647\u0630\u0647 \u0627\u0644\u062d\u0645\u0644\u0629\u060c \u0627\u0644\u062a\u064a \u0628\u062f\u0623\u0647\u0627 \u0623\u0635\u062f\u0642\u0627\u0621 \u0627\u0644\u0634\u0639\u0628 \u0627\u0644\u0643\u0631\u062f\u064a \u0639\u0644\u0649 \u0627\u0644\u0645\u0633\u062a\u0648\u0649 \u0627\u0644\u0639\u0627\u0644\u0645\u064a\u060c \u0644\u064a\u0633\u062a \u0645\u062d\u0636 \u0635\u062f\u0641\u0629\u060c \u0641\u0647\u064a \u062a\u062a\u0648\u0627\u0641\u0642 \u0645\u0639 \u0631\u0648\u062d \u0627\u0644\u062d\u0631\u064a\u0629\u060c \u0644\u0623\u0646 \u0647\u0646\u0627\u0643 \u0627\u0639\u062a\u0642\u0627\u062f\u0627\u064b \u0648\u0623\u0645\u0644\u0627\u064b \u0623\u0646\u0647 \u0633\u064a\u062a\u0645 \u0628\u0646\u0627\u0621 \u062d\u064a\u0627\u0629 \u062f\u064a\u0645\u0642\u0631\u0627\u0637\u064a\u0629 \u0648\u062a\u062d\u0631\u0631\u064a\u0629 \u0645\u0646 \u0623\u062c\u0644 \u0627\u0644\u0639\u0627\u0644\u0645 \u0645\u0646 \u062e\u0644\u0627\u0644 \u0646\u0645\u0648\u0630\u062c \u0627\u0644\u0642\u0627\u0626\u062f \u0648\u0623\u0641\u0643\u0627\u0631\u0647 \u0627\u0644\u0645\u0646\u0627\u0647\u0636\u0629 \u0644\u0644\u0646\u0638\u0627\u0645 \u0627\u0644\u0631\u0623\u0633\u0645\u0627\u0644\u064a \u0627\u0644\u062d\u062f\u064a\u062b.<\/p>\n<p style=\"direction: rtl;\">\u0648\u062f\u0639\u062a \u062d\u0631\u0643\u0629 \u0627\u0644\u0645\u0631\u0623\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629 \u0641\u064a \u0623\u0648\u0631\u0648\u0628\u0627 \u0641\u064a \u062e\u062a\u0627\u0645 \u0628\u064a\u0627\u0646\u0647\u0627\u060c \u0643\u0644 \u0627\u0644\u0623\u0635\u062f\u0642\u0627\u0621 \u0627\u0644\u062f\u0648\u0644\u064a\u064a\u0646 \u0648\u0627\u0644\u0645\u0646\u0638\u0645\u0627\u062a \u0627\u0644\u062f\u0648\u0644\u064a\u0629 \u0648\u0645\u0646\u0638\u0645\u0627\u062a \u0627\u0644\u0645\u0631\u0623\u0629 \u0627\u0644\u0643\u0631\u062f\u0633\u062a\u0627\u0646\u064a\u0629 \u0644\u0644\u0645\u0634\u0627\u0631\u0643\u0629 \u0641\u064a \u062d\u0645\u0644\u0629 &#8220;\u0627\u0644\u062d\u0631\u064a\u0629 \u0644\u0644\u0642\u0627\u0626\u062f \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0623\u0648\u062c\u0644\u0627\u0646\u060c \u0627\u0644\u062d\u0644 \u0627\u0644\u0633\u064a\u0627\u0633\u064a \u0644\u0644\u0642\u0636\u064a\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0623\u0639\u0644\u0646\u062a \u062d\u0631\u0643\u0629 \u0627\u0644\u0645\u0631\u0623\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629 \u0641\u064a \u0623\u0648\u0631\u0648\u0628\u0627 \u0639\u0646 \u062a\u0628\u0646\u064a\u0647\u0627 \u0644\u062d\u0645\u0644\u0629 &#8220;\u0627\u0644\u062d\u0631\u064a\u0629 \u0644\u0644\u0642\u0627\u0626\u062f \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0623\u0648\u062c\u0644\u0627\u0646\u060c \u0627\u0644\u062d\u0644 \u0627\u0644\u0633\u064a\u0627\u0633\u064a \u0644\u0644\u0642\u0636\u064a\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629&#8221;\u060c \u0648\u0639\u0628\u0631\u062a \u0639\u0646 \u0625\u064a\u0645\u0627\u0646\u0647\u0627 \u0628\u0623\u0646 \u0627\u0644\u0634\u0639\u0628 \u0633\u064a\u062a\u0648\u062c \u0646\u0636\u0627\u0644\u0647 \u0628\u062a\u062d\u0642\u064a\u0642 \u0627\u0644\u062d\u0631\u064a\u0629 \u0627\u0644\u062c\u0633\u062f\u064a\u0629 \u0644\u0644\u0642\u0627\u0626\u062f. \u0623\u0637\u0644\u0642\u062a \u0627\u0644\u0646\u0642\u0627\u0628\u0627\u062a \u0627\u0644\u0639\u0627\u0644\u0645\u064a\u0629 \u0648\u0627\u0644\u0623\u062d\u0632\u0627\u0628 \u0627\u0644\u0633\u064a\u0627\u0633\u064a\u0629 \u0641\u064a \u0623\u0631\u0628\u0639\u0629\u064d \u0648\u0633\u0628\u0639\u064a\u0646 \u0645\u062f\u064a\u0646\u0629 \u062d\u0648\u0644 \u0627\u0644\u0639\u0627\u0644\u0645 \u0641\u064a \u0627\u0644\u0639\u0627\u0634\u0631\u0650 \u0645\u0646 \u062a\u0634\u0631\u064a\u0646 \u0627\u0644\u0623\u0648\u0644 \u0627\u0644\u062c\u0627\u0631\u064a \u062d\u0645\u0644\u0629 &#8220;\u0627\u0644\u062d\u0631\u064a\u0629 \u0644\u0644\u0642\u0627\u0626\u062f \u0623\u0648\u062c\u0644\u0627\u0646\u060c\u0627\u0644\u062d\u0644 \u0627\u0644\u0633\u064a\u0627\u0633\u064a \u0644\u0644\u0642\u0636\u064a\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629&#8221;. \u0648\u0641\u064a \u0627\u0644\u0633\u064a\u0627\u0642 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":126838,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"jnews_override_counter":[],"jnews_post_split":[],"footnotes":""},"categories":[50],"tags":[],"class_list":["post-198466","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-50"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u062d\u0631\u0643\u0629 \u0627\u0644\u0645\u0631\u0623\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629 \u0641\u064a \u0623\u0648\u0631\u0648\u0628\u0627: \u0644\u0646\u062a\u0628\u0646\u0649 \u0627\u0644\u062d\u0645\u0644\u0629 \u0627\u0644\u0639\u0627\u0644\u0645\u064a\u0629 \u0644\u062d\u0631\u064a\u0629 \u0627\u0644\u0642\u0627\u0626\u062f \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0623\u0648\u062c\u0644\u0627\u0646 - \u0641\u0636\u0627\u0626\u064a\u0629 \u0631\u0648\u0646\u0627\u0647\u064a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ronahi.tv\/ar\/archives\/198466\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u062d\u0631\u0643\u0629 \u0627\u0644\u0645\u0631\u0623\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629 \u0641\u064a \u0623\u0648\u0631\u0648\u0628\u0627: \u0644\u0646\u062a\u0628\u0646\u0649 \u0627\u0644\u062d\u0645\u0644\u0629 \u0627\u0644\u0639\u0627\u0644\u0645\u064a\u0629 \u0644\u062d\u0631\u064a\u0629 \u0627\u0644\u0642\u0627\u0626\u062f \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0623\u0648\u062c\u0644\u0627\u0646 - \u0641\u0636\u0627\u0626\u064a\u0629 \u0631\u0648\u0646\u0627\u0647\u064a\" \/>\n<meta property=\"og:description\" content=\"\u0623\u0639\u0644\u0646\u062a \u062d\u0631\u0643\u0629 \u0627\u0644\u0645\u0631\u0623\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629 \u0641\u064a \u0623\u0648\u0631\u0648\u0628\u0627 \u0639\u0646 \u062a\u0628\u0646\u064a\u0647\u0627 \u0644\u062d\u0645\u0644\u0629 &#8220;\u0627\u0644\u062d\u0631\u064a\u0629 \u0644\u0644\u0642\u0627\u0626\u062f \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0623\u0648\u062c\u0644\u0627\u0646\u060c \u0627\u0644\u062d\u0644 \u0627\u0644\u0633\u064a\u0627\u0633\u064a \u0644\u0644\u0642\u0636\u064a\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629&#8221;\u060c \u0648\u0639\u0628\u0631\u062a \u0639\u0646 \u0625\u064a\u0645\u0627\u0646\u0647\u0627 \u0628\u0623\u0646 \u0627\u0644\u0634\u0639\u0628 \u0633\u064a\u062a\u0648\u062c \u0646\u0636\u0627\u0644\u0647 \u0628\u062a\u062d\u0642\u064a\u0642 \u0627\u0644\u062d\u0631\u064a\u0629 \u0627\u0644\u062c\u0633\u062f\u064a\u0629 \u0644\u0644\u0642\u0627\u0626\u062f. \u0623\u0637\u0644\u0642\u062a \u0627\u0644\u0646\u0642\u0627\u0628\u0627\u062a \u0627\u0644\u0639\u0627\u0644\u0645\u064a\u0629 \u0648\u0627\u0644\u0623\u062d\u0632\u0627\u0628 \u0627\u0644\u0633\u064a\u0627\u0633\u064a\u0629 \u0641\u064a \u0623\u0631\u0628\u0639\u0629\u064d \u0648\u0633\u0628\u0639\u064a\u0646 \u0645\u062f\u064a\u0646\u0629 \u062d\u0648\u0644 \u0627\u0644\u0639\u0627\u0644\u0645 \u0641\u064a \u0627\u0644\u0639\u0627\u0634\u0631\u0650 \u0645\u0646 \u062a\u0634\u0631\u064a\u0646 \u0627\u0644\u0623\u0648\u0644 \u0627\u0644\u062c\u0627\u0631\u064a \u062d\u0645\u0644\u0629 &#8220;\u0627\u0644\u062d\u0631\u064a\u0629 \u0644\u0644\u0642\u0627\u0626\u062f \u0623\u0648\u062c\u0644\u0627\u0646\u060c\u0627\u0644\u062d\u0644 \u0627\u0644\u0633\u064a\u0627\u0633\u064a \u0644\u0644\u0642\u0636\u064a\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629&#8221;. \u0648\u0641\u064a \u0627\u0644\u0633\u064a\u0627\u0642 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ronahi.tv\/ar\/archives\/198466\" \/>\n<meta property=\"og:site_name\" content=\"\u0641\u0636\u0627\u0626\u064a\u0629 \u0631\u0648\u0646\u0627\u0647\u064a\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RonahiTvOfficial\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-18T11:51:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ronahi.tv\/ar\/wp-content\/uploads\/2022\/04\/\u062d\u0631\u0643\u0629-\u0627\u0644\u0645\u0631\u0623\u0629-\u0627\u0644\u0643\u0631\u062f\u064a\u0629-\u0623\u0648\u0631\u0648\u0628\u0627.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"feAdVw8fgi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RonahiTV\" \/>\n<meta name=\"twitter:site\" content=\"@RonahiTV\" \/>\n<meta name=\"twitter:label1\" content=\"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629\" \/>\n\t<meta name=\"twitter:data1\" content=\"feAdVw8fgi\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 \u062f\u0642\u0627\u0626\u0642\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/archives\\\/198466#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/archives\\\/198466\"},\"author\":{\"name\":\"feAdVw8fgi\",\"@id\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/#\\\/schema\\\/person\\\/8730c8d8a25e97356470d3cb1a2a1429\"},\"headline\":\"\u062d\u0631\u0643\u0629 \u0627\u0644\u0645\u0631\u0623\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629 \u0641\u064a \u0623\u0648\u0631\u0648\u0628\u0627: \u0644\u0646\u062a\u0628\u0646\u0649 \u0627\u0644\u062d\u0645\u0644\u0629 \u0627\u0644\u0639\u0627\u0644\u0645\u064a\u0629 \u0644\u062d\u0631\u064a\u0629 \u0627\u0644\u0642\u0627\u0626\u062f \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0623\u0648\u062c\u0644\u0627\u0646\",\"datePublished\":\"2023-10-18T11:51:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/archives\\\/198466\"},\"wordCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/archives\\\/198466#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/\u062d\u0631\u0643\u0629-\u0627\u0644\u0645\u0631\u0623\u0629-\u0627\u0644\u0643\u0631\u062f\u064a\u0629-\u0623\u0648\u0631\u0648\u0628\u0627.jpg\",\"articleSection\":[\"\u0627\u0644\u0645\u0631\u0623\u0629\"],\"inLanguage\":\"ar\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/archives\\\/198466\",\"url\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/archives\\\/198466\",\"name\":\"\u062d\u0631\u0643\u0629 \u0627\u0644\u0645\u0631\u0623\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629 \u0641\u064a \u0623\u0648\u0631\u0648\u0628\u0627: \u0644\u0646\u062a\u0628\u0646\u0649 \u0627\u0644\u062d\u0645\u0644\u0629 \u0627\u0644\u0639\u0627\u0644\u0645\u064a\u0629 \u0644\u062d\u0631\u064a\u0629 \u0627\u0644\u0642\u0627\u0626\u062f \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0623\u0648\u062c\u0644\u0627\u0646 - \u0641\u0636\u0627\u0626\u064a\u0629 \u0631\u0648\u0646\u0627\u0647\u064a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/archives\\\/198466#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/archives\\\/198466#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/\u062d\u0631\u0643\u0629-\u0627\u0644\u0645\u0631\u0623\u0629-\u0627\u0644\u0643\u0631\u062f\u064a\u0629-\u0623\u0648\u0631\u0648\u0628\u0627.jpg\",\"datePublished\":\"2023-10-18T11:51:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/archives\\\/198466#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ronahi.tv\\\/ar\\\/archives\\\/198466\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/archives\\\/198466#primaryimage\",\"url\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/\u062d\u0631\u0643\u0629-\u0627\u0644\u0645\u0631\u0623\u0629-\u0627\u0644\u0643\u0631\u062f\u064a\u0629-\u0623\u0648\u0631\u0648\u0628\u0627.jpg\",\"contentUrl\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/\u062d\u0631\u0643\u0629-\u0627\u0644\u0645\u0631\u0623\u0629-\u0627\u0644\u0643\u0631\u062f\u064a\u0629-\u0623\u0648\u0631\u0648\u0628\u0627.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/archives\\\/198466#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u062d\u0631\u0643\u0629 \u0627\u0644\u0645\u0631\u0623\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629 \u0641\u064a \u0623\u0648\u0631\u0648\u0628\u0627: \u0644\u0646\u062a\u0628\u0646\u0649 \u0627\u0644\u062d\u0645\u0644\u0629 \u0627\u0644\u0639\u0627\u0644\u0645\u064a\u0629 \u0644\u062d\u0631\u064a\u0629 \u0627\u0644\u0642\u0627\u0626\u062f \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0623\u0648\u062c\u0644\u0627\u0646\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/#website\",\"url\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/\",\"name\":\"\u0641\u0636\u0627\u0626\u064a\u0629 \u0631\u0648\u0646\u0627\u0647\u064a\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/#organization\",\"name\":\"ronahi.tv\",\"url\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/logoronahi.png\",\"contentUrl\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/logoronahi.png\",\"width\":100,\"height\":48,\"caption\":\"ronahi.tv\"},\"image\":{\"@id\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RonahiTvOfficial\\\/\",\"https:\\\/\\\/x.com\\\/RonahiTV\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCiH6yCKVhI6UBqtT9FfIaAg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/#\\\/schema\\\/person\\\/8730c8d8a25e97356470d3cb1a2a1429\",\"name\":\"feAdVw8fgi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/405097e3cbbb6a62a71e0352a4f4edbcf0c5c91ae14cc546efc8e7ad10c35b4d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/405097e3cbbb6a62a71e0352a4f4edbcf0c5c91ae14cc546efc8e7ad10c35b4d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/405097e3cbbb6a62a71e0352a4f4edbcf0c5c91ae14cc546efc8e7ad10c35b4d?s=96&d=mm&r=g\",\"caption\":\"feAdVw8fgi\"},\"url\":\"https:\\\/\\\/ronahi.tv\\\/ar\\\/archives\\\/author\\\/feadvw8fgi\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u062d\u0631\u0643\u0629 \u0627\u0644\u0645\u0631\u0623\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629 \u0641\u064a \u0623\u0648\u0631\u0648\u0628\u0627: \u0644\u0646\u062a\u0628\u0646\u0649 \u0627\u0644\u062d\u0645\u0644\u0629 \u0627\u0644\u0639\u0627\u0644\u0645\u064a\u0629 \u0644\u062d\u0631\u064a\u0629 \u0627\u0644\u0642\u0627\u0626\u062f \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0623\u0648\u062c\u0644\u0627\u0646 - \u0641\u0636\u0627\u0626\u064a\u0629 \u0631\u0648\u0646\u0627\u0647\u064a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ronahi.tv\/ar\/archives\/198466","og_locale":"ar_AR","og_type":"article","og_title":"\u062d\u0631\u0643\u0629 \u0627\u0644\u0645\u0631\u0623\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629 \u0641\u064a \u0623\u0648\u0631\u0648\u0628\u0627: \u0644\u0646\u062a\u0628\u0646\u0649 \u0627\u0644\u062d\u0645\u0644\u0629 \u0627\u0644\u0639\u0627\u0644\u0645\u064a\u0629 \u0644\u062d\u0631\u064a\u0629 \u0627\u0644\u0642\u0627\u0626\u062f \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0623\u0648\u062c\u0644\u0627\u0646 - \u0641\u0636\u0627\u0626\u064a\u0629 \u0631\u0648\u0646\u0627\u0647\u064a","og_description":"\u0623\u0639\u0644\u0646\u062a \u062d\u0631\u0643\u0629 \u0627\u0644\u0645\u0631\u0623\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629 \u0641\u064a \u0623\u0648\u0631\u0648\u0628\u0627 \u0639\u0646 \u062a\u0628\u0646\u064a\u0647\u0627 \u0644\u062d\u0645\u0644\u0629 &#8220;\u0627\u0644\u062d\u0631\u064a\u0629 \u0644\u0644\u0642\u0627\u0626\u062f \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0623\u0648\u062c\u0644\u0627\u0646\u060c \u0627\u0644\u062d\u0644 \u0627\u0644\u0633\u064a\u0627\u0633\u064a \u0644\u0644\u0642\u0636\u064a\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629&#8221;\u060c \u0648\u0639\u0628\u0631\u062a \u0639\u0646 \u0625\u064a\u0645\u0627\u0646\u0647\u0627 \u0628\u0623\u0646 \u0627\u0644\u0634\u0639\u0628 \u0633\u064a\u062a\u0648\u062c \u0646\u0636\u0627\u0644\u0647 \u0628\u062a\u062d\u0642\u064a\u0642 \u0627\u0644\u062d\u0631\u064a\u0629 \u0627\u0644\u062c\u0633\u062f\u064a\u0629 \u0644\u0644\u0642\u0627\u0626\u062f. \u0623\u0637\u0644\u0642\u062a \u0627\u0644\u0646\u0642\u0627\u0628\u0627\u062a \u0627\u0644\u0639\u0627\u0644\u0645\u064a\u0629 \u0648\u0627\u0644\u0623\u062d\u0632\u0627\u0628 \u0627\u0644\u0633\u064a\u0627\u0633\u064a\u0629 \u0641\u064a \u0623\u0631\u0628\u0639\u0629\u064d \u0648\u0633\u0628\u0639\u064a\u0646 \u0645\u062f\u064a\u0646\u0629 \u062d\u0648\u0644 \u0627\u0644\u0639\u0627\u0644\u0645 \u0641\u064a \u0627\u0644\u0639\u0627\u0634\u0631\u0650 \u0645\u0646 \u062a\u0634\u0631\u064a\u0646 \u0627\u0644\u0623\u0648\u0644 \u0627\u0644\u062c\u0627\u0631\u064a \u062d\u0645\u0644\u0629 &#8220;\u0627\u0644\u062d\u0631\u064a\u0629 \u0644\u0644\u0642\u0627\u0626\u062f \u0623\u0648\u062c\u0644\u0627\u0646\u060c\u0627\u0644\u062d\u0644 \u0627\u0644\u0633\u064a\u0627\u0633\u064a \u0644\u0644\u0642\u0636\u064a\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629&#8221;. \u0648\u0641\u064a \u0627\u0644\u0633\u064a\u0627\u0642 [&hellip;]","og_url":"https:\/\/ronahi.tv\/ar\/archives\/198466","og_site_name":"\u0641\u0636\u0627\u0626\u064a\u0629 \u0631\u0648\u0646\u0627\u0647\u064a","article_publisher":"https:\/\/www.facebook.com\/RonahiTvOfficial\/","article_published_time":"2023-10-18T11:51:34+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/ronahi.tv\/ar\/wp-content\/uploads\/2022\/04\/\u062d\u0631\u0643\u0629-\u0627\u0644\u0645\u0631\u0623\u0629-\u0627\u0644\u0643\u0631\u062f\u064a\u0629-\u0623\u0648\u0631\u0648\u0628\u0627.jpg","type":"image\/jpeg"}],"author":"feAdVw8fgi","twitter_card":"summary_large_image","twitter_creator":"@RonahiTV","twitter_site":"@RonahiTV","twitter_misc":{"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629":"feAdVw8fgi","\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631":"3 \u062f\u0642\u0627\u0626\u0642"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ronahi.tv\/ar\/archives\/198466#article","isPartOf":{"@id":"https:\/\/ronahi.tv\/ar\/archives\/198466"},"author":{"name":"feAdVw8fgi","@id":"https:\/\/ronahi.tv\/ar\/#\/schema\/person\/8730c8d8a25e97356470d3cb1a2a1429"},"headline":"\u062d\u0631\u0643\u0629 \u0627\u0644\u0645\u0631\u0623\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629 \u0641\u064a \u0623\u0648\u0631\u0648\u0628\u0627: \u0644\u0646\u062a\u0628\u0646\u0649 \u0627\u0644\u062d\u0645\u0644\u0629 \u0627\u0644\u0639\u0627\u0644\u0645\u064a\u0629 \u0644\u062d\u0631\u064a\u0629 \u0627\u0644\u0642\u0627\u0626\u062f \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0623\u0648\u062c\u0644\u0627\u0646","datePublished":"2023-10-18T11:51:34+00:00","mainEntityOfPage":{"@id":"https:\/\/ronahi.tv\/ar\/archives\/198466"},"wordCount":0,"publisher":{"@id":"https:\/\/ronahi.tv\/ar\/#organization"},"image":{"@id":"https:\/\/ronahi.tv\/ar\/archives\/198466#primaryimage"},"thumbnailUrl":"https:\/\/ronahi.tv\/ar\/wp-content\/uploads\/2022\/04\/\u062d\u0631\u0643\u0629-\u0627\u0644\u0645\u0631\u0623\u0629-\u0627\u0644\u0643\u0631\u062f\u064a\u0629-\u0623\u0648\u0631\u0648\u0628\u0627.jpg","articleSection":["\u0627\u0644\u0645\u0631\u0623\u0629"],"inLanguage":"ar"},{"@type":"WebPage","@id":"https:\/\/ronahi.tv\/ar\/archives\/198466","url":"https:\/\/ronahi.tv\/ar\/archives\/198466","name":"\u062d\u0631\u0643\u0629 \u0627\u0644\u0645\u0631\u0623\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629 \u0641\u064a \u0623\u0648\u0631\u0648\u0628\u0627: \u0644\u0646\u062a\u0628\u0646\u0649 \u0627\u0644\u062d\u0645\u0644\u0629 \u0627\u0644\u0639\u0627\u0644\u0645\u064a\u0629 \u0644\u062d\u0631\u064a\u0629 \u0627\u0644\u0642\u0627\u0626\u062f \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0623\u0648\u062c\u0644\u0627\u0646 - \u0641\u0636\u0627\u0626\u064a\u0629 \u0631\u0648\u0646\u0627\u0647\u064a","isPartOf":{"@id":"https:\/\/ronahi.tv\/ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ronahi.tv\/ar\/archives\/198466#primaryimage"},"image":{"@id":"https:\/\/ronahi.tv\/ar\/archives\/198466#primaryimage"},"thumbnailUrl":"https:\/\/ronahi.tv\/ar\/wp-content\/uploads\/2022\/04\/\u062d\u0631\u0643\u0629-\u0627\u0644\u0645\u0631\u0623\u0629-\u0627\u0644\u0643\u0631\u062f\u064a\u0629-\u0623\u0648\u0631\u0648\u0628\u0627.jpg","datePublished":"2023-10-18T11:51:34+00:00","breadcrumb":{"@id":"https:\/\/ronahi.tv\/ar\/archives\/198466#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ronahi.tv\/ar\/archives\/198466"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/ronahi.tv\/ar\/archives\/198466#primaryimage","url":"https:\/\/ronahi.tv\/ar\/wp-content\/uploads\/2022\/04\/\u062d\u0631\u0643\u0629-\u0627\u0644\u0645\u0631\u0623\u0629-\u0627\u0644\u0643\u0631\u062f\u064a\u0629-\u0623\u0648\u0631\u0648\u0628\u0627.jpg","contentUrl":"https:\/\/ronahi.tv\/ar\/wp-content\/uploads\/2022\/04\/\u062d\u0631\u0643\u0629-\u0627\u0644\u0645\u0631\u0623\u0629-\u0627\u0644\u0643\u0631\u062f\u064a\u0629-\u0623\u0648\u0631\u0648\u0628\u0627.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/ronahi.tv\/ar\/archives\/198466#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ronahi.tv\/ar\/"},{"@type":"ListItem","position":2,"name":"\u062d\u0631\u0643\u0629 \u0627\u0644\u0645\u0631\u0623\u0629 \u0627\u0644\u0643\u0631\u062f\u064a\u0629 \u0641\u064a \u0623\u0648\u0631\u0648\u0628\u0627: \u0644\u0646\u062a\u0628\u0646\u0649 \u0627\u0644\u062d\u0645\u0644\u0629 \u0627\u0644\u0639\u0627\u0644\u0645\u064a\u0629 \u0644\u062d\u0631\u064a\u0629 \u0627\u0644\u0642\u0627\u0626\u062f \u0639\u0628\u062f \u0627\u0644\u0644\u0647 \u0623\u0648\u062c\u0644\u0627\u0646"}]},{"@type":"WebSite","@id":"https:\/\/ronahi.tv\/ar\/#website","url":"https:\/\/ronahi.tv\/ar\/","name":"\u0641\u0636\u0627\u0626\u064a\u0629 \u0631\u0648\u0646\u0627\u0647\u064a","description":"","publisher":{"@id":"https:\/\/ronahi.tv\/ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ronahi.tv\/ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/ronahi.tv\/ar\/#organization","name":"ronahi.tv","url":"https:\/\/ronahi.tv\/ar\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/ronahi.tv\/ar\/#\/schema\/logo\/image\/","url":"https:\/\/ronahi.tv\/ar\/wp-content\/uploads\/2019\/05\/logoronahi.png","contentUrl":"https:\/\/ronahi.tv\/ar\/wp-content\/uploads\/2019\/05\/logoronahi.png","width":100,"height":48,"caption":"ronahi.tv"},"image":{"@id":"https:\/\/ronahi.tv\/ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RonahiTvOfficial\/","https:\/\/x.com\/RonahiTV","https:\/\/www.youtube.com\/channel\/UCiH6yCKVhI6UBqtT9FfIaAg"]},{"@type":"Person","@id":"https:\/\/ronahi.tv\/ar\/#\/schema\/person\/8730c8d8a25e97356470d3cb1a2a1429","name":"feAdVw8fgi","image":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/secure.gravatar.com\/avatar\/405097e3cbbb6a62a71e0352a4f4edbcf0c5c91ae14cc546efc8e7ad10c35b4d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/405097e3cbbb6a62a71e0352a4f4edbcf0c5c91ae14cc546efc8e7ad10c35b4d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/405097e3cbbb6a62a71e0352a4f4edbcf0c5c91ae14cc546efc8e7ad10c35b4d?s=96&d=mm&r=g","caption":"feAdVw8fgi"},"url":"https:\/\/ronahi.tv\/ar\/archives\/author\/feadvw8fgi"}]}},"_links":{"self":[{"href":"https:\/\/ronahi.tv\/ar\/wp-json\/wp\/v2\/posts\/198466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ronahi.tv\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ronahi.tv\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ronahi.tv\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ronahi.tv\/ar\/wp-json\/wp\/v2\/comments?post=198466"}],"version-history":[{"count":1,"href":"https:\/\/ronahi.tv\/ar\/wp-json\/wp\/v2\/posts\/198466\/revisions"}],"predecessor-version":[{"id":198467,"href":"https:\/\/ronahi.tv\/ar\/wp-json\/wp\/v2\/posts\/198466\/revisions\/198467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ronahi.tv\/ar\/wp-json\/wp\/v2\/media\/126838"}],"wp:attachment":[{"href":"https:\/\/ronahi.tv\/ar\/wp-json\/wp\/v2\/media?parent=198466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ronahi.tv\/ar\/wp-json\/wp\/v2\/categories?post=198466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ronahi.tv\/ar\/wp-json\/wp\/v2\/tags?post=198466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}